{"id":110,"date":"2019-06-12T18:29:41","date_gmt":"2019-06-12T16:29:41","guid":{"rendered":"http:\/\/www.cantinalemandolare.com\/?p=110"},"modified":"2024-03-25T11:54:57","modified_gmt":"2024-03-25T10:54:57","slug":"menini-soave-d-o-c-classico","status":"publish","type":"post","link":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/","title":{"rendered":"Menini &#8211; SOAVE D.O.C. CLASSICO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1560348159439{margin-top: 80px !important;margin-bottom: 80px !important;}&#8221; z_index=&#8221;&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;380&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column_inner][vc_column_inner el_class=&#8221;prod-descr&#8221; width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1560352851339{padding-left: 30px !important;}&#8221;][vc_column_text]<\/p>\n<h1>Menini<\/h1>\n<p>[\/vc_column_text][vc_column_text]SOAVE D.O.C. CLASSICO[\/vc_column_text][vc_empty_space height=&#8221;30px&#8221;][vc_column_text]<strong>Vitigno<\/strong><br \/>\nGarganega 100%[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Vigneti<\/strong><br \/>\nSituati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Tecniche produttive<\/strong><br \/>\nLe uve vengono raccolte a mano i primi del mese di Ottobre quando si \u00e8 raggiunto un ottimale indice di maturazione. Vengono diraspate e spremute in maniera soffice. Il mosto, decantato a freddo, viene fatto fermentare in serbatoi termocondizionati a basse temperature con lieviti selezionati di natura criofila. Il vino viene poi lasciato maturare sulle proprie fecce fini in serbatoi di acciaio inox al fine di valorizzarne la struttura e la persistenza olfattiva.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Caratteristiche organolettiche<\/strong><br \/>\n[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Colore<\/strong><br \/>\nGiallo dorato con riflessi verdognoli.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Profumo<\/strong><br \/>\nFine, dolce, caldo, fruttato con sentori di agrumi e di banana, leggermente floreale.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Sapore<\/strong><br \/>\nRotondo, armonico, mediamente lungo e con il caratteristico retrogusto di mandorla tipico dell&#8217;uva Garganega.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Gradazione alcolica<\/strong><br \/>\n12,5 % vol.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]<strong>Servizio ed abbinamenti<\/strong><br \/>\nSi serve alla temperatura di 10-12\u00b0C. Si abbina con antipasti, primi piatti, pesce, carni bianche. E&#8217; consigliato anche come vino a tutto pasto.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<h2>Menini<\/h2>\n<p>SOAVE D.O.C. CLASSICO<\/p>\n","protected":false},"author":2,"featured_media":380,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-vini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Menini - SOAVE D.O.C. CLASSICO - Cantina le Mandolare<\/title>\n<meta name=\"description\" content=\"Vitigni Situati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Menini - SOAVE D.O.C. CLASSICO - Cantina le Mandolare\" \/>\n<meta property=\"og:description\" content=\"Vitigni Situati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/\" \/>\n<meta property=\"og:site_name\" content=\"Cantina le Mandolare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Le-Mandolare-272665786145368\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-12T16:29:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T10:54:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/06\/Menini-e1711014791369.png\" \/>\n\t<meta property=\"og:image:width\" content=\"265\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"enrico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"enrico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/\"},\"author\":{\"name\":\"enrico\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#\\\/schema\\\/person\\\/1b2511ed1deeb7ff25a327fbec283ca1\"},\"headline\":\"Menini &#8211; SOAVE D.O.C. CLASSICO\",\"datePublished\":\"2019-06-12T16:29:41+00:00\",\"dateModified\":\"2024-03-25T10:54:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/\"},\"wordCount\":386,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Menini-e1711014791369.png\",\"articleSection\":[\"Vini\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/\",\"url\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/\",\"name\":\"Menini - SOAVE D.O.C. CLASSICO - Cantina le Mandolare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Menini-e1711014791369.png\",\"datePublished\":\"2019-06-12T16:29:41+00:00\",\"dateModified\":\"2024-03-25T10:54:57+00:00\",\"description\":\"Vitigni Situati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Menini-e1711014791369.png\",\"contentUrl\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Menini-e1711014791369.png\",\"width\":265,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/menini-soave-d-o-c-classico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menini &#8211; SOAVE D.O.C. CLASSICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/\",\"name\":\"Cantina le Mandolare\",\"description\":\"Vino Soave\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#organization\",\"name\":\"Azienda Agricola Le Mandolare di Dal Bosco e Rodighiero\",\"url\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo-blu.svg\",\"contentUrl\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo-blu.svg\",\"width\":1,\"height\":1,\"caption\":\"Azienda Agricola Le Mandolare di Dal Bosco e Rodighiero\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Le-Mandolare-272665786145368\\\/\",\"https:\\\/\\\/www.instagram.com\\\/le_mandolare\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cantinalemandolare.com\\\/it\\\/#\\\/schema\\\/person\\\/1b2511ed1deeb7ff25a327fbec283ca1\",\"name\":\"enrico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53d424ccf7f64bb4ac88f6ba6da863f19966280aa1f378445dd5547970efc454?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53d424ccf7f64bb4ac88f6ba6da863f19966280aa1f378445dd5547970efc454?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53d424ccf7f64bb4ac88f6ba6da863f19966280aa1f378445dd5547970efc454?s=96&d=mm&r=g\",\"caption\":\"enrico\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menini - SOAVE D.O.C. CLASSICO - Cantina le Mandolare","description":"Vitigni Situati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/","og_locale":"it_IT","og_type":"article","og_title":"Menini - SOAVE D.O.C. CLASSICO - Cantina le Mandolare","og_description":"Vitigni Situati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.","og_url":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/","og_site_name":"Cantina le Mandolare","article_publisher":"https:\/\/www.facebook.com\/Le-Mandolare-272665786145368\/","article_published_time":"2019-06-12T16:29:41+00:00","article_modified_time":"2024-03-25T10:54:57+00:00","og_image":[{"width":265,"height":1000,"url":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/06\/Menini-e1711014791369.png","type":"image\/png"}],"author":"enrico","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"enrico","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#article","isPartOf":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/"},"author":{"name":"enrico","@id":"https:\/\/www.cantinalemandolare.com\/it\/#\/schema\/person\/1b2511ed1deeb7ff25a327fbec283ca1"},"headline":"Menini &#8211; SOAVE D.O.C. CLASSICO","datePublished":"2019-06-12T16:29:41+00:00","dateModified":"2024-03-25T10:54:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/"},"wordCount":386,"commentCount":0,"publisher":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/#organization"},"image":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/06\/Menini-e1711014791369.png","articleSection":["Vini"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/","url":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/","name":"Menini - SOAVE D.O.C. CLASSICO - Cantina le Mandolare","isPartOf":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#primaryimage"},"image":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/06\/Menini-e1711014791369.png","datePublished":"2019-06-12T16:29:41+00:00","dateModified":"2024-03-25T10:54:57+00:00","description":"Vitigni Situati sulle colline di Castelcerino, localit\u00e0 Menini, coltivati a pergola veronese, di et\u00e0 media di 20 anni con esposizione a Sud-Est.","breadcrumb":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#primaryimage","url":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/06\/Menini-e1711014791369.png","contentUrl":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/06\/Menini-e1711014791369.png","width":265,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.cantinalemandolare.com\/it\/menini-soave-d-o-c-classico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cantinalemandolare.com\/it\/"},{"@type":"ListItem","position":2,"name":"Menini &#8211; SOAVE D.O.C. CLASSICO"}]},{"@type":"WebSite","@id":"https:\/\/www.cantinalemandolare.com\/it\/#website","url":"https:\/\/www.cantinalemandolare.com\/it\/","name":"Cantina le Mandolare","description":"Vino Soave","publisher":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cantinalemandolare.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.cantinalemandolare.com\/it\/#organization","name":"Azienda Agricola Le Mandolare di Dal Bosco e Rodighiero","url":"https:\/\/www.cantinalemandolare.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cantinalemandolare.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/05\/logo-blu.svg","contentUrl":"https:\/\/www.cantinalemandolare.com\/wp-content\/uploads\/2019\/05\/logo-blu.svg","width":1,"height":1,"caption":"Azienda Agricola Le Mandolare di Dal Bosco e Rodighiero"},"image":{"@id":"https:\/\/www.cantinalemandolare.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Le-Mandolare-272665786145368\/","https:\/\/www.instagram.com\/le_mandolare\/"]},{"@type":"Person","@id":"https:\/\/www.cantinalemandolare.com\/it\/#\/schema\/person\/1b2511ed1deeb7ff25a327fbec283ca1","name":"enrico","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/53d424ccf7f64bb4ac88f6ba6da863f19966280aa1f378445dd5547970efc454?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53d424ccf7f64bb4ac88f6ba6da863f19966280aa1f378445dd5547970efc454?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53d424ccf7f64bb4ac88f6ba6da863f19966280aa1f378445dd5547970efc454?s=96&d=mm&r=g","caption":"enrico"}}]}},"_links":{"self":[{"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":8,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":404,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/posts\/110\/revisions\/404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/media\/380"}],"wp:attachment":[{"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cantinalemandolare.com\/it\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}